{"id":3598,"date":"2019-04-07T23:26:27","date_gmt":"2019-04-07T22:26:27","guid":{"rendered":"https:\/\/mcamps.com\/?p=3598"},"modified":"2019-04-07T23:29:07","modified_gmt":"2019-04-07T22:29:07","slug":"infarma-2019-congreso-farmacia","status":"publish","type":"post","link":"https:\/\/mcampsco-cp176.wordpresstemporal.com\/fra\/infarma-2019-congreso-farmacia\/","title":{"rendered":"Chronique d'Infarma 2019 : le congr\u00e8s revient \u00e0 Barcelone"},"content":{"rendered":"<blockquote><p><b>En mars dernier s'est tenu \u00e0 Barcelone le 31e congr\u00e8s et salon europ\u00e9en de l'officine, Infarma 2019. Un rendez-vous o\u00f9, ann\u00e9e apr\u00e8s ann\u00e9e, et en alternance entre Barcelone et Madrid, l'ensemble du secteur pharmaceutique se retrouve autour de la figure de l'officine.<\/b><\/p><\/blockquote>\n<p>Cette fois-ci, elle s'est tenue du 19 au 21 mai et le th\u00e8me de ce grand \u00e9v\u00e9nement, organis\u00e9 par les Ordres des pharmaciens de Barcelone et de Madrid et par Interalia, \u00e9tait <strong><em>La sant\u00e9 nous relie.<\/em><\/strong>\u00a0Nous pensons qu'il s'agit d'une allusion claire \u00e0 la n\u00e9cessit\u00e9 de se connecter - de collaborer - avec le reste des professionnels du secteur de la sant\u00e9 afin d'offrir un meilleur service au patient\/consommateur final.<\/p>\n<h2><strong>Infarma 2019 bat des records de fr\u00e9quentation et d'exposants<\/strong><\/h2>\n<p>Comme \u00e0 l'accoutum\u00e9e, l'\u00e9dition de cette ann\u00e9e d'Infarma <a href=\"https:\/\/www.infarma.es\/infarma2019\/es\/News\/View\/8906-infarma-barcelona-2019-cierra-sus-puertas-con-un-10-mas-de-participantes-respecto-a-l\" target=\"_blank\" rel=\"noopener\">a r\u00e9ussi \u00e0 battre des records<\/a>, Tant au niveau du nombre de participants - 3 480 congressistes et plus de 33 700 visiteurs ont \u00e9t\u00e9 accr\u00e9dit\u00e9s, soit 10% de participants en plus par rapport \u00e0 2017 - que du nombre d'exposants - 406 laboratoires et entreprises du secteur pharmaceutique \u00e9taient pr\u00e9sents sur le salon, ce qui repr\u00e9sente une augmentation de 7% par rapport \u00e0 l'\u00e9dition pr\u00e9c\u00e9dente.<\/p>\n<p>S'il est une chose ind\u00e9niable, c'est que le secteur pharmaceutique continue de cro\u00eetre \u00e0 un bon rythme, tant dans notre pays que dans l'ensemble de l'Union europ\u00e9enne. C'est pourquoi, ann\u00e9e apr\u00e8s ann\u00e9e, le Bureau technique pharmaceutique et sa directrice, Merc\u00e8 Camps, participent \u00e0 Infarma, o\u00f9 sont pr\u00e9sent\u00e9es les derni\u00e8res tendances du secteur et o\u00f9 l'on peut rencontrer les principaux acteurs du secteur dans la p\u00e9ninsule.<\/p>\n<div id=\"attachment_3600\" style=\"width: 850px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" aria-describedby=\"caption-attachment-3600\" class=\"wp-image-3600\" src=\"https:\/\/mcamps.com\/wp-content\/uploads\/2019\/04\/Dise\u00f1o-sin-t\u00edtulo-1.png\" alt=\"Infarma 2019 visitantes COFB\" width=\"840\" height=\"350\" title=\"\" srcset=\"https:\/\/mcamps.com\/wp-content\/uploads\/2019\/04\/Dise\u00f1o-sin-t\u00edtulo-1.png 960w, https:\/\/mcamps.com\/wp-content\/uploads\/2019\/04\/Dise\u00f1o-sin-t\u00edtulo-1-300x125.png 300w, https:\/\/mcamps.com\/wp-content\/uploads\/2019\/04\/Dise\u00f1o-sin-t\u00edtulo-1-768x320.png 768w\" sizes=\"(max-width: 840px) 100vw, 840px\" \/><p id=\"caption-attachment-3600\" class=\"wp-caption-text\">\u00c0 gauche, deux visiteurs de la rencontre Infarma 2019 devant le stand du COFB. \u00c0 droite, le slogan de l'\u00e9dition de cette ann\u00e9e : La sant\u00e9 nous relie.<\/p><\/div>\n<h2><strong>Deux profils de participants : visiteurs et congressistes \u00e0 Infarma 2019. <\/strong><\/h2>\n<p>Infarma 2019 a accueilli 33 779 visiteurs. Un peu plus de 50% d'entre eux sont des pharmaciens, le reste \u00e9tant constitu\u00e9 d'\u00e9tudiants et d'autres travailleurs du secteur. Tous ont acc\u00e8s aux 126 posters scientifiques pr\u00e9sent\u00e9s - les 3 premiers re\u00e7oivent un prix lors de la c\u00e9r\u00e9monie de cl\u00f4ture d'Infarma - et au Salon des exposants.<\/p>\n<p>Les congressistes, quant \u00e0 eux, concentrent leur visite sur les ateliers et les classes professionnelles du congr\u00e8s. Ainsi, en plus de visiter les affiches professionnelles et le Salon, ils assistent \u00e9galement aux 7 tables rondes d'actualit\u00e9 et aux 32 classes - auxquelles participent un total de 170 professionnels de la pharmacie et de la sant\u00e9, y compris des orateurs et des mod\u00e9rateurs professionnels - organis\u00e9es par les coll\u00e8ges pendant les 3 jours du Congr\u00e8s.<\/p>\n<p>Parmi les discussions qui ont eu lieu, nous aimerions souligner la classe professionnelle de \u201c...\".\u201c<em>Protocoles de phytoth\u00e9rapie pour une action efficace<\/em>\u201dqui a \u00e9t\u00e9 anim\u00e9e par notre coll\u00e8gue <b>Mar\u00eda Jos\u00e9 Alonso<\/b>, pharmacien dipl\u00f4m\u00e9 en phytoth\u00e9rapie. Le d\u00e9bat a port\u00e9 sur ces protocoles, qui sont en cours d'\u00e9laboration gr\u00e2ce \u00e0 la collaboration des associations de pharmaciens de toute l'Espagne, sur la base des monographies existantes, telles que celles de l'ESCOP (European Scientific Cooperative On Phytotherapy), et sur les informations de l'Agence europ\u00e9enne des m\u00e9dicaments (EMA) et d'autres sources officielles ou contrast\u00e9es. Vous trouverez ici <a href=\"https:\/\/www.infarma.es\/infarma2019\/es\/News\/View\/8948-los-protocolos-de-fitoterapia-permitiran-estandarizar-el-servicio-de-consulta-y-recom\" target=\"_blank\" rel=\"noopener\">la chronique d'Infarma<\/a>.<\/p>\n<p>Le jeudi 21, les deux pr\u00e9sidents de la COFB et de la COFM ont cl\u00f4tur\u00e9 l'\u00e9dition 2019 et pr\u00e9sent\u00e9, comme le veut la tradition, la prochaine \u00e9dition d'Infarma 2020. Retenez donc les dates : les 10, 11 et 12 mars \u00e0 la Feria de Madrid.<\/p>\n<p><img decoding=\"async\" class=\"aligncenter size-full wp-image-3601\" src=\"https:\/\/mcamps.com\/wp-content\/uploads\/2019\/04\/Dise\u00f1o-sin-t\u00edtulo-2.png\" alt=\"Farmaforum 2019 39 Symposium AEFI\" width=\"960\" height=\"250\" title=\"\" srcset=\"https:\/\/mcamps.com\/wp-content\/uploads\/2019\/04\/Dise\u00f1o-sin-t\u00edtulo-2.png 960w, https:\/\/mcamps.com\/wp-content\/uploads\/2019\/04\/Dise\u00f1o-sin-t\u00edtulo-2-300x78.png 300w, https:\/\/mcamps.com\/wp-content\/uploads\/2019\/04\/Dise\u00f1o-sin-t\u00edtulo-2-768x200.png 768w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><\/p>\n<h2><b>Autres activit\u00e9s dans le secteur : Farmaforum et symposium de l'AEFI<\/b><\/h2>\n<p>Outre la participation \u00e0 Infarma, un grand nombre d'\u00e9v\u00e9nements industriels importants ont eu lieu entre la fin du mois de mars et le d\u00e9but du mois d'avril.<\/p>\n<p>Parmi eux, nous aimerions en souligner deux auxquels nous avons particip\u00e9 :<\/p>\n<h4><font color=\"#003366\">AEFI Symposiun (Barcelone, 14\/03\/2019 - 15\/03\/2019)<\/font><\/h4>\n<p>Le <b>39\u00e8me symposium de l'AEFI<\/b> -l'Association espagnole des pharmaciens industriels, <a href=\"https:\/\/mcamps.com\" target=\"_blank\" rel=\"noopener\">dont GTF M. Camps est membre<\/a>- s'est tenue \u00e0 l'h\u00f4tel Barcel\u00f3 de Barcelone, avec pour slogan <em>Form\u00e9 et \u00e0 l'\u00e9coute des nouveaux d\u00e9fis<\/em><strong><em>. <\/em><\/strong>La r\u00e9union a permis de mettre sur la table les d\u00e9fis auxquels le secteur est confront\u00e9 \u00e0 l'approche de la sortie du Royaume-Uni de l'UE.<\/p>\n<h4><font color=\"#003366\">Farmaforum (Madrid, 28\/03\/2019 - 29\/03\/2019)<\/font><\/h4>\n<p style=\"font-size: 16px; font-weight: 400;\">Les<b> 6e Forum de l'industrie pharmaceutique, biopharmaceutique, cosm\u00e9tique et des technologies de laboratoire<\/b>. Lors de cette derni\u00e8re \u00e9dition, le forum s'est dot\u00e9 de deux domaines sp\u00e9ciaux que nous trouvons tr\u00e8s int\u00e9ressants : Biotechforum, sur l'industrie des biotechnologies, et Cosm\u00e9ticaforum, sur l'industrie des cosm\u00e9tiques.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Este mes de marzo se ha celebrado en Barcelona el 31\u00aa Congreso y Sal\u00f3n Europeo de Oficina de Farmacia, Infarma 2019. Un encuentro donde, a\u00f1o a a\u00f1o, y de forma alterna entre Barcelona y Madrid, se da cita el conjunto del sector farmac\u00e9utico alrededor de la figura de la oficina de farmacia. En esta ocasi\u00f3n [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3599,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","inline_featured_image":false,"footnotes":""},"categories":[50,99,371,199],"tags":[181,876,878,882,880,874,884],"class_list":["post-3598","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-cosmeticos","category-curiosidades","category-productos-sanitarios","tag-aefi","tag-cofg","tag-cofm","tag-farmaforum","tag-fitoterapia","tag-infarma-2019","tag-simposium-de-aefi"],"_links":{"self":[{"href":"https:\/\/mcampsco-cp176.wordpresstemporal.com\/fra\/wp-json\/wp\/v2\/posts\/3598","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mcampsco-cp176.wordpresstemporal.com\/fra\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mcampsco-cp176.wordpresstemporal.com\/fra\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mcampsco-cp176.wordpresstemporal.com\/fra\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mcampsco-cp176.wordpresstemporal.com\/fra\/wp-json\/wp\/v2\/comments?post=3598"}],"version-history":[{"count":0,"href":"https:\/\/mcampsco-cp176.wordpresstemporal.com\/fra\/wp-json\/wp\/v2\/posts\/3598\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mcampsco-cp176.wordpresstemporal.com\/fra\/wp-json\/wp\/v2\/media\/3599"}],"wp:attachment":[{"href":"https:\/\/mcampsco-cp176.wordpresstemporal.com\/fra\/wp-json\/wp\/v2\/media?parent=3598"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mcampsco-cp176.wordpresstemporal.com\/fra\/wp-json\/wp\/v2\/categories?post=3598"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mcampsco-cp176.wordpresstemporal.com\/fra\/wp-json\/wp\/v2\/tags?post=3598"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}